{"id":4662,"date":"2024-07-29T12:26:20","date_gmt":"2024-07-29T12:26:20","guid":{"rendered":"http:\/\/radioazul.com.ar\/?p=4662"},"modified":"2024-07-29T12:26:21","modified_gmt":"2024-07-29T12:26:21","slug":"asuncion-de-la-subdirectora-de-institutos-policiales","status":"publish","type":"post","link":"https:\/\/radioazul.com.ar\/index.php\/2024\/07\/29\/asuncion-de-la-subdirectora-de-institutos-policiales\/","title":{"rendered":"Asunci\u00f3n de la Subdirectora de Institutos Policiales"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En el marco del acto institucional llevado a cabo en la Direcci\u00f3n de &#8220;Institutos Policiales&#8221; la Comisario Inspector Sonia Mariela Capellino asumio como Subdirectora de la direccci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dicha ceremonia se llevo a cabo el d\u00eda lunes 29 de julio, presidida por la Directora de Institutos Policiales Comisario General Mar\u00eda De Los Angeles Facciano frente a todo el cuerpo de cadetes de la Escuela Superiror de Oficiales &#8220;Dr. Salvador Mac\u00eda&#8221;, jefes de divisi\u00f3n y personal policial . <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"577\" height=\"1024\" src=\"https:\/\/radioazul.com.ar\/wp-content\/uploads\/2024\/07\/7cad938e-8c5f-4b0d-b251-7677e3ecf602-577x1024.jpg\" alt=\"\" class=\"wp-image-4663\" srcset=\"https:\/\/radioazul.com.ar\/wp-content\/uploads\/2024\/07\/7cad938e-8c5f-4b0d-b251-7677e3ecf602-577x1024.jpg 577w, https:\/\/radioazul.com.ar\/wp-content\/uploads\/2024\/07\/7cad938e-8c5f-4b0d-b251-7677e3ecf602-169x300.jpg 169w, https:\/\/radioazul.com.ar\/wp-content\/uploads\/2024\/07\/7cad938e-8c5f-4b0d-b251-7677e3ecf602-768x1364.jpg 768w, https:\/\/radioazul.com.ar\/wp-content\/uploads\/2024\/07\/7cad938e-8c5f-4b0d-b251-7677e3ecf602-865x1536.jpg 865w, https:\/\/radioazul.com.ar\/wp-content\/uploads\/2024\/07\/7cad938e-8c5f-4b0d-b251-7677e3ecf602.jpg 901w\" sizes=\"auto, (max-width: 577px) 100vw, 577px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco del acto institucional llevado a cabo en la Direcci\u00f3n de &#8220;Institutos Policiales&#8221; la Comisario Inspector Sonia Mariela Capellino asumio como Subdirectora de la direccci\u00f3n. Dicha ceremonia se llevo a cabo el d\u00eda lunes 29 de julio, presidida por la Directora de Institutos Policiales Comisario General Mar\u00eda De Los Angeles Facciano frente a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4664,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4662","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/radioazul.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/4662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioazul.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioazul.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioazul.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radioazul.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=4662"}],"version-history":[{"count":1,"href":"https:\/\/radioazul.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/4662\/revisions"}],"predecessor-version":[{"id":4665,"href":"https:\/\/radioazul.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/4662\/revisions\/4665"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioazul.com.ar\/index.php\/wp-json\/wp\/v2\/media\/4664"}],"wp:attachment":[{"href":"https:\/\/radioazul.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=4662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioazul.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=4662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioazul.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=4662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}